{"id":53501,"date":"2024-06-17T09:06:09","date_gmt":"2024-06-17T02:06:09","guid":{"rendered":"http:\/\/localhost\/wordpress\/orima\/?page_id=53501"},"modified":"2025-10-16T09:38:22","modified_gmt":"2025-10-16T09:38:22","slug":"about-us","status":"publish","type":"page","link":"https:\/\/mywatcheslists.com\/retro\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"53501\" class=\"elementor elementor-53501\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5070ddf e-flex e-con-boxed e-con e-parent\" data-id=\"5070ddf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47daaa7 e-con-full e-flex e-con e-child\" data-id=\"47daaa7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a87d75 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1a87d75\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37f9678 e-flex e-con-boxed e-con e-parent\" data-id=\"37f9678\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-401590b e-con-full e-flex e-con e-child\" data-id=\"401590b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-843688a elementor-widget elementor-widget-bwp-image-banner\" data-id=\"843688a\" data-element_type=\"widget\" data-widget_type=\"bwp-image-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bwp-widget-banner\">\t\r\n\t<div class=\"banner-wrapper hover-effect effect_5\">\r\n\t\t\t\t\t<div class=\"bwp-image content-image\">\r\n\t\t\t\t<a href=\"#\"><img decoding=\"async\" class=\"fade-in lazyload\" src=\"https:\/\/mywatcheslists.com\/retro\/wp-content\/uploads\/2025\/10\/Gemini_Generated_Image_kvv7whkvv7whkvv7.png\" alt=\"Banner Image\"><\/a>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"banner-wrapper-infor\">\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-476e786 e-con-full e-flex e-con e-child\" data-id=\"476e786\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a8f46e elementor-widget elementor-widget-heading\" data-id=\"9a8f46e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ABOUT US\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad10b06 elementor-widget elementor-widget-heading\" data-id=\"ad10b06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Retro Fashion Design Studio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1639eb5 elementor-widget elementor-widget-text-editor\" data-id=\"1639eb5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"bgLayers_comp-lsvsalg7\" class=\"MW5IWV\" data-hook=\"bgLayers\" data-motion-part=\"BG_LAYER comp-lsvsalg7\"><div id=\"bgMedia_comp-lsvsalg7\" class=\"VgO9Yg\" data-motion-part=\"BG_MEDIA comp-lsvsalg7\">Welcome to Retro Fashion Design Studio, a boutique owned by DAYA SARA JACOB that specializes in handmade and self-designed clothes. Driven by a passion for fashion and unique designs, this business was created to share a vision of style. Explore our extensive collection that caters to various styles and preferences. mission is to provide high-quality clothing that makes you feel confident and comfortable.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27335e9 elementor-widget elementor-widget-bwp-button\" data-id=\"27335e9\" data-element_type=\"widget\" data-widget_type=\"bwp-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bwp-button-widget\">\n\t\t\t<a href=\"http:\/\/..\/shop\" class=\"bwp-button-link default bwp-button\" role=\"button\">\n\t\t\t\t\t\t<span class=\"bwp-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"bwp-button-text\">Shop now<\/span>\n\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b63094c e-flex e-con-boxed e-con e-parent\" data-id=\"b63094c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7efe5 elementor-widget elementor-widget-bwp-info-box\" data-id=\"1c7efe5\" data-element_type=\"widget\" data-widget_type=\"bwp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"bwp-info-box carousel\">\r\n\t\t<div class=\"bwp-swiper-slider swiper swiper-container-wrap-dots-outside\" data-swiper-id=\"1c7efe5\" data-slider-settings='{&quot;speed&quot;:500,&quot;slides_per_view&quot;:4,&quot;slides_to_scroll&quot;:1,&quot;space_between&quot;:30,&quot;auto_height&quot;:false,&quot;loop&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;slides_per_view_mobile&quot;:1,&quot;slides_to_scroll_mobile&quot;:1,&quot;space_between_mobile&quot;:15,&quot;slides_per_view_tablet&quot;:2,&quot;slides_to_scroll_tablet&quot;:1,&quot;space_between_tablet&quot;:15,&quot;slides_per_view_tablet_extra&quot;:4}'>\r\n\t\t\t<div id=\"swiper-wrapper-6a57098c3ebe6\" class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide info-box elementor-repeater-item-3025e40 hover-effect effect_1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-icon elementor-animation-wobble-horizontal\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"46\" viewBox=\"0 0 50 46\" fill=\"none\"><path d=\"M49.9527 11.6381C49.8859 11.4181 49.7382 11.2316 49.5393 11.1162L29.2072 0.102946C29.0833 0.0353961 28.9445 0 28.8035 0C28.6624 0 28.5236 0.0353961 28.3998 0.102946L8.06763 11.1162C7.8067 11.267 7.62372 11.5533 7.62456 11.8609V22.027H0.847174C0.622489 22.027 0.407007 22.1162 0.248131 22.2751C0.0892555 22.434 0 22.6494 0 22.8741C0 23.0988 0.0892555 23.3143 0.248131 23.4732C0.407007 23.632 0.622489 23.7213 0.847174 23.7213H7.62456V27.11H3.38869C3.16401 27.11 2.94853 27.1993 2.78965 27.3581C2.63078 27.517 2.54152 27.7325 2.54152 27.9572C2.54152 28.1819 2.63078 28.3973 2.78965 28.5562C2.94853 28.7151 3.16401 28.8043 3.38869 28.8043H7.62456V33.8874C7.62463 34.04 7.66591 34.1897 7.74405 34.3208C7.82219 34.4519 7.93428 34.5594 8.06848 34.632L28.4006 45.6453C28.5277 45.7029 28.6624 45.7504 28.8039 45.7478C28.9454 45.7504 29.0801 45.7029 29.208 45.6453L49.5402 34.632C49.6742 34.5593 49.7861 34.4517 49.8641 34.3206C49.9421 34.1896 49.9833 34.0399 49.9832 33.8874C49.9011 33.4621 50.0798 12.1548 49.9527 11.6381ZM28.8039 1.81085L47.357 11.8609L38.9827 16.3975L21.0014 6.0374L28.8039 1.81085ZM19.2529 6.98454L37.2333 17.3446L28.8039 21.9109L10.2508 11.8609L19.2529 6.98454ZM9.31891 28.8043H15.2491C15.4738 28.8043 15.6893 28.7151 15.8482 28.5562C16.007 28.3973 16.0963 28.1819 16.0963 27.9572C16.0963 27.7325 16.007 27.517 15.8482 27.3581C15.6893 27.1993 15.4738 27.11 15.2491 27.11H9.31891V23.7213H12.7076C12.9323 23.7213 13.1478 23.632 13.3066 23.4732C13.4655 23.3143 13.5548 23.0988 13.5548 22.8741C13.5548 22.6494 13.4655 22.434 13.3066 22.2751C13.1478 22.1162 12.9323 22.027 12.7076 22.027H9.31891V13.2833L27.9567 23.379V43.4774L9.31891 33.3825V28.8043ZM48.2889 33.3825L29.6511 43.4782V23.379L38.1228 18.7899V27.11C38.127 28.2164 39.8129 28.2189 39.8172 27.11V17.8716L48.2889 13.2833V33.3825Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title\">\r\n\t\t\t\t\t\t\t\t\t\tFast delivery\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Fast delivery within 1-3 days<\/p>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide info-box elementor-repeater-item-f9fc8f6 hover-effect effect_1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-icon elementor-animation-wobble-horizontal\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"45\" viewBox=\"0 0 48 45\" fill=\"none\"><path d=\"M39.3243 33.5119C39.1518 33.7735 38.9741 34.0316 38.7912 34.286C38.6996 34.413 38.6067 34.5389 38.5124 34.6638C38.4946 34.6873 38.335 34.8945 38.4686 34.7223C38.4046 34.8046 38.34 34.8864 38.2747 34.9677C37.8683 35.4763 37.4361 35.964 36.9852 36.4335C36.5344 36.903 36.0599 37.3492 35.5684 37.7758C35.3323 37.9806 35.0906 38.179 34.8458 38.3734C34.8227 38.3918 34.6162 38.5521 34.7889 38.4191C34.582 38.578 34.3722 38.733 34.1595 38.8841C33.0929 39.6455 31.9528 40.3024 30.765 40.8553C30.6214 40.9218 30.477 40.9867 30.332 41.05C30.3046 41.0621 30.0608 41.1658 30.2645 41.0802C30.1913 41.1108 30.118 41.141 30.0445 41.1708C29.7253 41.301 29.4022 41.4216 29.0771 41.5359C28.4468 41.7578 27.8051 41.9461 27.1568 42.1073C26.5001 42.2707 25.8349 42.3988 25.1657 42.4988C25.135 42.5034 24.8638 42.5409 25.0904 42.5107C24.8456 42.5429 24.6003 42.5709 24.3546 42.5947C23.9968 42.63 23.638 42.6542 23.279 42.6716C21.999 42.7333 20.7137 42.6749 19.4434 42.5089C19.6924 42.5414 19.4435 42.5078 19.4008 42.5017C19.328 42.4912 19.2554 42.4799 19.1828 42.4686C19.0379 42.4461 18.8933 42.4213 18.7489 42.3959C18.4376 42.3409 18.1279 42.2774 17.8194 42.2086C17.2313 42.0775 16.6497 41.9183 16.075 41.7375C15.5057 41.5584 14.9451 41.3524 14.393 41.126C14.3545 41.1102 14.1306 41.0149 14.354 41.1101C14.2885 41.0822 14.2233 41.0536 14.158 41.0251C14.0278 40.9678 13.8982 40.9092 13.7692 40.8494C13.49 40.7204 13.2144 40.5839 12.9411 40.4429C11.8957 39.9038 10.8985 39.2729 9.95636 38.5693C9.90001 38.5272 9.84408 38.4846 9.78811 38.442C9.97854 38.5871 9.78795 38.4416 9.75559 38.4163C9.64507 38.3294 9.53541 38.2415 9.42663 38.1525C9.19071 37.9601 8.95984 37.7616 8.73233 37.5594C8.29495 37.1707 7.87557 36.7621 7.47145 36.3391C7.06712 35.9159 6.68234 35.4742 6.31395 35.0194C6.22565 34.91 6.13844 34.7997 6.05232 34.6886C6.19937 34.8777 6.05281 34.6876 6.028 34.6549C5.98565 34.5988 5.94357 34.5424 5.90174 34.4859C5.71999 34.2408 5.54477 33.9911 5.37367 33.7385C4.71237 32.7623 4.13721 31.7285 3.64631 30.6568C3.58729 30.5273 3.52954 30.3972 3.47307 30.2665C3.37628 30.0435 3.55016 30.4525 3.45631 30.228C3.42877 30.1622 3.40194 30.0961 3.3751 30.03C3.25848 29.7429 3.14963 29.4527 3.04571 29.1608C2.84445 28.5954 2.6702 28.0207 2.51763 27.4405C2.36341 26.8537 2.23742 26.2596 2.13398 25.6619C2.10896 25.5172 2.08614 25.3722 2.06413 25.2271C2.05309 25.1544 2.04281 25.0815 2.03252 25.0086C2.06766 25.2575 2.03274 25.0082 2.02727 24.9654C1.98672 24.6466 1.95506 24.3268 1.92892 24.0067C1.82709 22.7603 1.83994 21.505 1.95469 20.2601C1.97547 20.039 1.99969 19.8182 2.02733 19.5977C2.03263 19.555 2.06686 19.3055 2.03258 19.5545C2.07597 19.2395 2.12803 18.9257 2.18546 18.613C2.29484 18.0174 2.43273 17.4272 2.59268 16.8432C2.75092 16.2654 2.93659 15.6952 3.1432 15.133C3.24177 14.8647 3.34708 14.5991 3.45641 14.3351C3.54946 14.1103 3.37713 14.5199 3.47318 14.2966C3.5013 14.2311 3.53012 14.166 3.55889 14.1009C3.62618 13.9493 3.69527 13.7984 3.76614 13.6484C4.26749 12.5822 4.86274 11.5608 5.53298 10.5921C5.69355 10.3608 5.85864 10.1328 6.02816 9.90805C6.0528 9.87526 6.19888 9.68483 6.05248 9.87435C6.09544 9.8187 6.139 9.76352 6.18249 9.70829C6.28423 9.5797 6.38743 9.45227 6.49206 9.32603C6.86484 8.87488 7.25825 8.44093 7.66654 8.02176C8.07484 7.60264 8.50226 7.20233 8.94334 6.81798C9.15552 6.63369 9.37132 6.45359 9.5906 6.2778C9.64535 6.23371 9.70058 6.19021 9.75575 6.14672C9.788 6.12127 9.97827 5.97519 9.78827 6.121C9.91866 6.02131 10.0502 5.9231 10.1828 5.82638C11.1327 5.13155 12.1428 4.52023 13.1939 3.9913C13.4476 3.8636 13.7046 3.74226 13.9633 3.62484C14.093 3.56619 14.2233 3.50887 14.3542 3.45289C14.1311 3.54878 14.3546 3.45289 14.3931 3.43698C14.481 3.40055 14.5694 3.3652 14.6578 3.32995C15.2129 3.10877 15.7784 2.91394 16.3502 2.74049C16.9278 2.56527 17.5136 2.41779 18.104 2.2925C18.39 2.23181 18.6775 2.17851 18.9656 2.12965C19.1105 2.10537 19.2556 2.08259 19.4009 2.0613C19.4435 2.05498 19.6924 2.0207 19.4435 2.05407C19.541 2.041 19.6388 2.02905 19.7365 2.01732C20.9769 1.86829 22.2304 1.83439 23.4775 1.90151C23.7751 1.91752 24.0723 1.94125 24.369 1.96964C24.5899 1.99112 24.8105 2.01609 25.0306 2.04453C25.1382 2.05862 25.1282 2.05728 25.0006 2.04046C25.0492 2.04721 25.0978 2.05418 25.1464 2.0613C25.749 2.14851 26.3473 2.2647 26.9401 2.40333C27.526 2.54036 28.1053 2.70524 28.6774 2.8916C28.9501 2.98042 29.2205 3.07615 29.4893 3.176C29.6233 3.22576 29.7565 3.27756 29.8895 3.33C29.9559 3.3562 30.0221 3.38309 30.0882 3.40993C30.1314 3.4275 30.4257 3.55199 30.1931 3.45289C31.2794 3.91561 32.324 4.47427 33.3185 5.11034C33.8129 5.4265 34.2924 5.76537 34.7591 6.121C34.5686 5.97589 34.7592 6.12138 34.7916 6.14672C34.9574 6.27698 35.1212 6.40967 35.2831 6.54473C35.5171 6.73934 35.746 6.94011 35.9714 7.14447C36.8387 7.93064 37.6373 8.79164 38.3649 9.70824C38.4085 9.76337 38.4519 9.81873 38.495 9.8743C38.3479 9.68526 38.4945 9.87527 38.5192 9.908C38.604 10.0203 38.6876 10.1335 38.7701 10.2475C38.9495 10.4943 39.1224 10.7459 39.291 11.0002C39.6161 11.4907 39.9186 11.996 40.2021 12.5115C40.4871 13.0296 40.7478 13.5609 40.9886 14.1008C41.0175 14.1658 41.0459 14.2311 41.0743 14.2964C41.1711 14.5195 40.9972 14.1105 41.091 14.335C41.1459 14.4667 41.1994 14.5991 41.2515 14.732C41.3654 15.0205 41.4714 15.3121 41.5724 15.6053C41.9662 16.7479 42.2557 17.9255 42.4494 19.1182C42.469 19.2391 42.487 19.3603 42.5045 19.4815C42.5405 19.7303 42.4781 19.2748 42.5107 19.5244C42.555 19.8675 42.5909 20.2115 42.6184 20.5563C42.6653 21.1301 42.6861 21.7059 42.6871 22.2815C42.688 22.7925 43.1129 23.2189 43.6245 23.2189C44.1349 23.2189 44.5629 22.7925 44.562 22.2815C44.5532 17.2469 42.8324 12.3939 39.7343 8.43782C36.7528 4.63096 32.4695 1.87735 27.7906 0.681549C22.8516 -0.580728 17.5833 -0.067118 12.952 2.03532C8.57265 4.02333 4.89745 7.521 2.62514 11.752C0.21726 16.2354 -0.540031 21.4532 0.377482 26.4484C1.2538 31.2195 3.79689 35.6558 7.40658 38.8851C11.1236 42.2104 15.8747 44.1858 20.8459 44.5227C26.3674 44.8968 31.8408 43.112 36.1716 39.6992C38.0357 38.2301 39.6381 36.438 40.9432 34.4582C41.2248 34.0311 41.0297 33.4233 40.6069 33.1756C40.148 32.9068 39.6049 33.0862 39.3243 33.5119Z\" fill=\"black\"><\/path><path d=\"M22.2736 20.9552C22.1241 20.9542 21.9753 20.9482 21.8263 20.9371C21.7527 20.9317 21.6794 20.9232 21.6062 20.9148C21.8555 20.9435 21.6104 20.9126 21.5662 20.9051C21.2588 20.8528 20.9576 20.768 20.6641 20.6638C20.5972 20.6396 20.5309 20.6141 20.4651 20.5872C20.6905 20.6774 20.469 20.5861 20.4297 20.5681C20.3018 20.509 20.1774 20.4425 20.0546 20.3736C19.9321 20.3051 19.8138 20.2294 19.697 20.1517C19.639 20.1125 19.5818 20.0722 19.5253 20.0308C19.4427 19.9689 19.4504 19.9753 19.5483 20.0501C19.5118 20.0212 19.4757 19.9918 19.44 19.9619C19.2245 19.7841 19.0265 19.586 18.8407 19.3777C18.7942 19.3256 18.7497 19.2717 18.7053 19.2179C18.5536 19.0341 18.8231 19.3778 18.6809 19.1864C18.5834 19.0551 18.4943 18.9178 18.4091 18.7783C18.3356 18.6583 18.2692 18.5342 18.2053 18.4089C18.1732 18.346 18.1436 18.2819 18.1139 18.2178C18.0127 17.9987 18.1879 18.4053 18.098 18.1807C17.9826 17.8922 17.8981 17.592 17.8337 17.2882C17.8187 17.2171 17.8065 17.1454 17.7943 17.0737C17.7525 16.828 17.8171 17.2813 17.7884 17.0325C17.7714 16.885 17.7635 16.7366 17.7584 16.5883C17.7534 16.4385 17.7574 16.2885 17.7645 16.1389C17.768 16.0648 17.7745 15.991 17.781 15.9172C17.7856 15.8683 17.7909 15.8195 17.7968 15.7708C17.779 15.8988 17.7782 15.9094 17.7943 15.8026C17.8389 15.5175 17.9117 15.2374 18.001 14.9633C18.023 14.8956 18.0478 14.8288 18.0724 14.7619C18.0872 14.7219 18.1813 14.4995 18.085 14.7231C18.1502 14.5719 18.225 14.4251 18.3036 14.2805C18.3706 14.1571 18.4448 14.0377 18.5211 13.9199C18.5596 13.8614 18.5992 13.8036 18.6398 13.7466C18.664 13.7122 18.8095 13.5239 18.6615 13.7129C18.8481 13.4747 19.0587 13.2559 19.2818 13.0518C19.3337 13.005 19.3864 12.9592 19.44 12.9144C19.4721 12.8872 19.66 12.7416 19.4692 12.8872C19.5805 12.8023 19.6967 12.7239 19.8141 12.6477C19.932 12.5714 20.0543 12.5018 20.1777 12.4348C20.2399 12.4015 20.3027 12.3695 20.3661 12.3387C20.4089 12.3176 20.6991 12.1919 20.4651 12.2891C20.8413 12.1328 21.237 12.0272 21.638 11.959C21.7448 11.9429 21.7342 11.9438 21.6062 11.9615C21.6549 11.9556 21.7037 11.9503 21.7526 11.9457C21.8758 11.9331 21.9996 11.9273 22.1234 11.9231C22.3473 11.9156 22.5715 11.9261 22.7945 11.9457C22.8434 11.9503 22.8922 11.9556 22.9409 11.9615C22.8129 11.9438 22.8023 11.9429 22.909 11.959C23.0286 11.9777 23.1469 12.0027 23.2649 12.0294C23.4747 12.0767 23.6804 12.1406 23.883 12.2125C23.928 12.2285 24.2214 12.3501 23.9885 12.2497C24.0966 12.2963 24.2022 12.3485 24.307 12.4019C24.4947 12.4977 24.6747 12.6079 24.85 12.7246C24.9276 12.7764 25.0029 12.8315 25.0778 12.8872C24.8776 12.7384 25.124 12.9288 25.1603 12.9595C25.3201 13.0949 25.4694 13.2423 25.6127 13.395C25.6764 13.4629 25.737 13.5335 25.7972 13.6046C25.8271 13.6404 25.8564 13.6765 25.8854 13.7129C25.7352 13.5263 25.8821 13.7122 25.907 13.7466C26.0303 13.9172 26.1404 14.097 26.2432 14.2805C26.289 14.3625 26.3312 14.4465 26.3728 14.5307C26.3934 14.573 26.4134 14.6156 26.4329 14.6585C26.5341 14.8776 26.3589 14.471 26.4488 14.6956C26.5284 14.8947 26.5922 15.0998 26.6476 15.3068C26.6726 15.3998 26.6931 15.4939 26.7131 15.5881C26.7253 15.6458 26.7834 16.0307 26.7499 15.7708C26.7784 15.992 26.7889 16.2152 26.7904 16.4382C26.7938 16.9491 27.2142 17.3756 27.7278 17.3756C28.2362 17.3756 28.6687 16.9492 28.6653 16.4382C28.6467 13.6911 26.8886 11.2946 24.3142 10.3807C23.0637 9.93683 21.6296 9.94331 20.368 10.3356C19.07 10.7394 17.9656 11.5575 17.1459 12.6319C15.6737 14.5617 15.5245 17.2056 16.5862 19.3552C17.6374 21.4834 19.9254 22.8143 22.2734 22.8301C22.7844 22.8335 23.2108 22.4011 23.2108 21.8927C23.2111 21.379 22.7846 20.9587 22.2736 20.9552Z\" fill=\"black\"><\/path><path d=\"M22.2739 22.8416C22.4234 22.8427 22.5722 22.8487 22.7213 22.8598C22.7948 22.8653 22.868 22.8737 22.9413 22.8821C22.692 22.8534 22.937 22.8843 22.9812 22.8918C23.2887 22.9441 23.5898 23.0289 23.8834 23.1331C23.9503 23.1568 24.0163 23.1833 24.0823 23.2097C23.8569 23.1195 24.0784 23.2107 24.1176 23.2288C24.2455 23.2879 24.3699 23.3545 24.4928 23.4233C24.6152 23.4919 24.7336 23.5674 24.8503 23.6453C24.9086 23.6841 24.9653 23.7251 25.022 23.7661C25.1046 23.828 25.097 23.8216 24.999 23.7468C25.0355 23.7757 25.0716 23.8052 25.1073 23.835C25.3227 24.0128 25.5208 24.2109 25.7066 24.4192C25.7531 24.4713 25.7975 24.5252 25.842 24.5791C25.9936 24.7629 25.7242 24.4191 25.8664 24.6105C25.9639 24.7418 26.0529 24.8792 26.1382 25.0185C26.2117 25.1385 26.278 25.2627 26.342 25.3879C26.3741 25.4509 26.4036 25.515 26.4333 25.579C26.5345 25.7981 26.3593 25.3915 26.4492 25.6161C26.5646 25.9047 26.6491 26.2048 26.7135 26.5086C26.7285 26.5797 26.7407 26.6515 26.7529 26.7231C26.7946 26.9688 26.7301 26.5155 26.7587 26.7644C26.7757 26.9118 26.7838 27.0602 26.7887 27.2086C26.7938 27.3584 26.7898 27.5083 26.7827 27.658C26.7793 27.732 26.7727 27.8059 26.7662 27.8797C26.7616 27.9286 26.7563 27.9774 26.7503 28.0261C26.7681 27.898 26.769 27.8874 26.7529 27.9942C26.7083 28.2793 26.6355 28.5594 26.5462 28.8335C26.5242 28.9013 26.4994 28.9681 26.4747 29.0349C26.4599 29.0749 26.3658 29.2973 26.4622 29.0737C26.3971 29.2249 26.3222 29.3717 26.2436 29.5163C26.1766 29.6397 26.1024 29.7591 26.0261 29.8769C25.9876 29.9354 25.9481 29.9932 25.9074 30.0502C25.8832 30.0846 25.7377 30.2729 25.8858 30.0839C25.6992 30.3221 25.4886 30.5409 25.2655 30.745C25.2137 30.7918 25.1609 30.8376 25.1073 30.8824C25.0753 30.9096 24.8873 31.0552 25.0782 30.9096C24.9668 30.9945 24.8507 31.073 24.7332 31.1491C24.6153 31.2256 24.4931 31.2951 24.3697 31.3621C24.3075 31.3954 24.2447 31.4274 24.1813 31.4582C24.1385 31.4794 23.8483 31.6049 24.0823 31.5078C23.7061 31.664 23.3105 31.7697 22.9094 31.8379C22.8026 31.854 22.8132 31.8531 22.9413 31.8353C22.8925 31.8413 22.8437 31.8466 22.7949 31.8512C22.6716 31.8637 22.5478 31.8696 22.424 31.8737C22.2001 31.8814 21.9759 31.8709 21.7529 31.8512C21.704 31.8466 21.6552 31.8413 21.6065 31.8353C21.7345 31.8531 21.7451 31.854 21.6383 31.8379C21.5188 31.8192 21.4004 31.7942 21.2824 31.7675C21.0725 31.7202 20.8668 31.6563 20.6643 31.5843C20.6192 31.5684 20.3259 31.4468 20.5587 31.5471C20.4506 31.5005 20.345 31.4484 20.2402 31.3949C20.0525 31.2991 19.8725 31.1889 19.6972 31.0722C19.6195 31.0205 19.5443 30.9653 19.4694 30.9096C19.6696 31.0584 19.4231 30.8681 19.3868 30.8373C19.227 30.7019 19.0777 30.5545 18.9344 30.4019C18.8707 30.3339 18.8101 30.2633 18.7499 30.1922C18.7201 30.1565 18.6907 30.1204 18.6617 30.0839C18.8119 30.2706 18.665 30.0847 18.6401 30.0502C18.5167 29.8796 18.4067 29.6998 18.3039 29.5163C18.258 29.4344 18.2158 29.3504 18.1742 29.2662C18.1537 29.2238 18.1336 29.1812 18.1141 29.1383C18.013 28.9192 18.1881 29.3258 18.0983 29.1013C18.0186 28.9022 17.9549 28.6971 17.8994 28.4901C17.8745 28.3971 17.854 28.303 17.834 28.2088C17.8218 28.1511 17.7636 27.7662 17.7971 28.0261C17.7686 27.8049 17.7582 27.5817 17.7567 27.3588C17.7533 26.8478 17.3329 26.4213 16.8193 26.4213C16.3109 26.4213 15.8784 26.8477 15.8819 27.3588C15.9004 30.1058 17.6587 32.5023 20.233 33.4161C21.4835 33.86 22.9176 33.8536 24.1791 33.4612C25.4771 33.0575 26.5815 32.2393 27.4011 31.1649C28.8733 29.2351 29.0225 26.5912 27.9609 24.4417C26.9098 22.3135 24.6218 20.9827 22.2738 20.9668C21.7628 20.9634 21.3364 21.3958 21.3364 21.9043C21.3365 22.4179 21.763 22.8383 22.2739 22.8416Z\" fill=\"black\"><\/path><path d=\"M21.3218 9.21674V35.3566C21.3218 35.8676 21.7482 36.294 22.2592 36.294C22.7703 36.294 23.1967 35.8676 23.1967 35.3566V9.21674C23.1967 8.7057 22.7703 8.2793 22.2592 8.2793C21.7482 8.2793 21.3218 8.70575 21.3218 9.21674ZM46.4034 18.19L42.9683 21.6251H44.294L40.8589 18.19C40.4977 17.8288 39.8943 17.8288 39.5332 18.19C39.172 18.5511 39.172 19.1546 39.5332 19.5157L42.9683 22.9508C43.3294 23.312 43.9328 23.312 44.294 22.9508L47.7291 19.5157C48.0902 19.1546 48.0902 18.5511 47.7291 18.19C47.3679 17.8288 46.7645 17.8288 46.4034 18.19Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title\">\r\n\t\t\t\t\t\t\t\t\t\tEasy Returns\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Easy returns within 14 days<\/p>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide info-box elementor-repeater-item-44ae299 hover-effect effect_1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-icon elementor-animation-wobble-horizontal\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"46\" viewBox=\"0 0 40 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M26.0856 16.4824C24.8817 15.2786 23.3479 14.4588 21.6782 14.1267C20.0084 13.7945 18.2777 13.965 16.7048 14.6165C15.1319 15.268 13.7876 16.3713 12.8417 17.7869C11.8959 19.2024 11.391 20.8667 11.391 22.5691C11.391 24.2716 11.8959 25.9359 12.8417 27.3514C13.7876 28.767 15.1319 29.8703 16.7048 30.5218C18.2777 31.1733 20.0084 31.3438 21.6782 31.0116C23.3479 30.6795 24.8817 29.8597 26.0856 28.6559C27.6997 27.0415 28.6064 24.852 28.6064 22.5691C28.6064 20.2862 27.6997 18.0968 26.0856 16.4824ZM19.9983 12.1013C22.0688 12.1013 24.0928 12.7153 25.8143 13.8656C27.5358 15.0159 28.8776 16.6509 29.6699 18.5638C30.4622 20.4767 30.6694 22.5816 30.2654 24.6122C29.8614 26.6429 28.8643 28.5082 27.4002 29.9721C25.9361 31.4361 24.0707 32.433 22.04 32.8369C20.0093 33.2407 17.9045 33.0332 15.9917 32.2408C14.0788 31.4483 12.444 30.1064 11.2938 28.3848C10.1437 26.6632 9.52988 24.6391 9.53007 22.5687C9.53032 19.7925 10.6333 17.1301 12.5965 15.1671C14.5596 13.2041 17.2221 12.1013 19.9983 12.1013ZM10.5722 3.68627C13.6867 2.82159 16.6989 1.62329 19.5563 0.112198C19.6904 0.03953 19.8404 0.00100354 19.9929 1.93428e-05C20.1455 -0.000964857 20.2959 0.0356236 20.431 0.106554C23.291 1.6211 26.3063 2.82195 29.4245 3.68815C32.5743 4.55817 35.8063 5.09751 39.0679 5.29743C39.1903 5.29681 39.3115 5.3204 39.4247 5.36684C39.5379 5.41329 39.6407 5.48167 39.7274 5.56805C39.814 5.65442 39.8827 5.75709 39.9295 5.87013C39.9763 5.98317 40.0002 6.10435 40 6.22669V17.7559C39.9313 24.8345 38.2722 30.5633 34.9906 35.0855C31.7091 39.6076 26.8201 42.8986 20.2965 45.091C20.1055 45.1554 19.8987 45.1554 19.7077 45.091C13.1841 42.8986 8.29795 39.6104 5.01356 35.0855C1.7414 30.5821 0.0832217 24.8815 0.00139421 17.8443C-0.000464738 17.813 -0.000464738 17.7816 0.00139421 17.7503V6.22669C0.00145054 5.99013 0.0918158 5.76251 0.254034 5.59033C0.416251 5.41815 0.638083 5.31439 0.874221 5.30025C4.15439 5.10253 7.4048 4.56159 10.5722 3.68627ZM19.9983 1.97072C25.6745 4.89864 31.7853 6.58598 38.1405 7.08917V17.7493C38.0738 24.4197 36.5303 29.7883 33.4792 33.9954C30.477 38.1338 25.9924 41.168 19.9946 43.2325C13.9967 41.168 9.5122 38.1319 6.50997 33.9954C3.47295 29.8052 1.93045 24.4573 1.85333 17.8189V7.09105C8.21142 6.58786 14.3221 4.90052 19.9983 1.97072ZM23.3326 18.9946C23.5002 18.8145 23.7325 18.7084 23.9784 18.6995C24.2243 18.6907 24.4636 18.7799 24.6437 18.9476C24.8238 19.1152 24.9299 19.3475 24.9388 19.5934C24.9476 19.8393 24.8584 20.0786 24.6907 20.2587L19.2102 26.1531C19.1191 26.2518 19.0077 26.3296 18.8836 26.381C18.7595 26.4324 18.6257 26.4562 18.4915 26.4507C18.3573 26.4452 18.2259 26.4107 18.1064 26.3494C17.9868 26.2881 17.8821 26.2015 17.7993 26.0957L15.2956 23.3211C15.214 23.2309 15.151 23.1256 15.1101 23.0111C15.0693 22.8966 15.0514 22.7751 15.0574 22.6537C15.0635 22.5322 15.0934 22.4132 15.1455 22.3033C15.1976 22.1934 15.2708 22.0949 15.361 22.0133C15.4511 21.9317 15.5565 21.8687 15.671 21.8278C15.7855 21.7869 15.907 21.769 16.0284 21.7751C16.1499 21.7812 16.2689 21.8111 16.3788 21.8632C16.4887 21.9153 16.5872 21.9885 16.6688 22.0787L18.5358 24.1413L23.3326 18.9946Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title\">\r\n\t\t\t\t\t\t\t\t\t\tPremium Quality\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Premium quality, handcrafted<\/p>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide info-box elementor-repeater-item-91c7785 hover-effect effect_1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-icon elementor-animation-wobble-horizontal\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"46\" height=\"46\" viewBox=\"0 0 46 46\" fill=\"none\"><path d=\"M25.5048 23.5617H21.6204L25.3003 18.8596C25.9137 18.0419 26.1692 16.9686 25.9648 15.9464C25.7603 14.873 25.0959 13.902 24.1759 13.3909C23.3071 12.8798 22.2849 12.7775 21.3138 13.0331C20.3427 13.2886 19.5249 13.902 19.0138 14.7708C18.8094 15.1286 18.9116 15.5886 19.3205 15.793C19.6783 15.9975 20.1383 15.8952 20.3427 15.4864C20.6494 14.9753 21.1093 14.6175 21.6716 14.4642C22.2338 14.3108 22.8471 14.362 23.3582 14.6686C23.8693 14.9753 24.2782 15.5375 24.3804 16.2019C24.4826 16.8152 24.3804 17.4285 24.0226 17.8885L19.4227 23.8684C19.2183 24.1239 19.2183 24.4306 19.3205 24.6861C19.4738 24.9417 19.7294 25.095 19.9849 25.095H25.4537C25.8626 25.095 26.2203 24.7372 26.2203 24.3284C26.2203 23.9195 25.9137 23.5617 25.5048 23.5617ZM34.2957 20.5973H33.7846V13.6975C33.7846 13.3398 33.5801 13.0842 33.2224 12.982C32.9157 12.8798 32.5579 13.0331 32.3535 13.2886L27.2425 20.9551C27.0892 21.2107 27.0892 21.5173 27.1914 21.7218C27.3447 21.9773 27.6003 22.1306 27.8558 22.1306H32.2002V24.2773C32.2002 24.6861 32.5579 25.0439 32.9668 25.0439C33.3757 25.0439 33.7335 24.6861 33.7335 24.2773V22.1306H34.2446C34.6534 22.1306 35.0112 21.7729 35.0112 21.364C35.0112 20.9551 34.7046 20.5973 34.2957 20.5973ZM32.2513 20.5973H29.338L32.2513 16.2019V20.5973Z\" fill=\"black\"><\/path><path d=\"M46 19.0128C46 8.53534 37.4647 0 26.9872 0C21.0073 0 15.4363 2.81104 11.8586 7.51314L11.0409 6.69538C10.7257 6.37951 10.3512 6.12891 9.93905 5.95793C9.52685 5.78695 9.08498 5.69893 8.63873 5.69893C8.19248 5.69893 7.75061 5.78695 7.33841 5.95793C6.92622 6.12891 6.55179 6.37951 6.23657 6.69538L2.40333 10.5286C-0.305488 13.2886 -0.714366 17.2751 1.12559 22.2328C2.70999 26.4749 6.03213 31.2281 10.4276 35.6235C16.2541 41.4501 23.5117 45.9988 29.3382 45.9988C31.6893 45.9988 33.7848 45.2833 35.4714 43.5967L39.3046 39.7634C40.6335 38.4346 40.6335 36.288 39.3046 34.9591L38.4869 34.1414C43.189 30.5126 46 24.9416 46 19.0128ZM38.2313 38.639L34.3981 42.4723C29.2871 47.5832 18.9629 41.91 11.552 34.448C7.25877 30.257 4.08996 25.7082 2.55666 21.6706C1.43225 18.6551 0.665599 14.4641 3.47664 11.653L7.30987 7.8198C7.66764 7.46203 8.12763 7.25759 8.63873 7.25759C9.09872 7.25759 9.60982 7.46203 9.96758 7.8198L14.5675 12.4197C14.9252 12.7775 15.1297 13.2374 15.1297 13.7485C15.1297 14.2596 14.9252 14.7196 14.5675 15.0774L11.9098 17.7351C11.092 18.5529 10.4276 20.1373 11.8075 23.1016C12.7275 25.0438 14.363 27.1904 16.6119 29.4392C18.8096 31.637 21.0073 33.3236 22.9495 34.2436C25.8627 35.6235 27.4982 34.9591 28.316 34.1414L30.9737 31.4836C31.6893 30.7681 32.8648 30.7681 33.5803 31.4836L38.1802 36.0835C38.9468 36.748 38.9468 37.9235 38.2313 38.639ZM37.3624 33.0169L34.6536 30.3081C34.3384 29.9922 33.964 29.7416 33.5518 29.5707C33.1396 29.3997 32.6977 29.3117 32.2515 29.3117C31.8052 29.3117 31.3633 29.3997 30.9511 29.5707C30.5389 29.7416 30.1645 29.9922 29.8493 30.3081L27.1916 32.9658C26.3227 33.8347 24.7894 33.3236 23.6139 32.7614C21.8762 31.9436 19.7807 30.3081 17.6852 28.2637C15.6408 26.2193 14.0053 24.1238 13.1875 22.335C12.6253 21.1595 12.1142 19.5751 12.9831 18.7573L15.6408 16.0996C16.3052 15.4863 16.6119 14.6174 16.6119 13.6974C16.6119 12.7775 16.2541 11.9597 15.6408 11.2953L12.932 8.58645C16.0497 4.34433 20.9562 1.73773 26.2205 1.53329V3.73102C26.2205 4.13989 26.5783 4.49766 26.9872 4.49766C27.396 4.49766 27.7538 4.13989 27.7538 3.73102V1.53329C36.8002 1.94217 44.0578 9.19977 44.4667 18.2462H41.6557C41.2468 18.2462 40.889 18.604 40.889 19.0128C40.889 19.4217 41.2468 19.7795 41.6557 19.7795H44.4667C44.2112 24.9927 41.6046 29.8992 37.3624 33.0169Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-title\">\r\n\t\t\t\t\t\t\t\t\t\tSupport 24\/7\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-description\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Customer care, 24\/7 support<\/p>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"swiper-pagination swiper-pagination-1c7efe5\"\n\t\t\t\tdata-widget-id=\"1c7efe5\"\n\t\t\t\t\t\t\t\t\tdata-dots-hide-over=\"991\"\n\t\t\t\t\t\t\t\t>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-749aaef e-flex e-con-boxed e-con e-parent\" data-id=\"749aaef\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0e5d014 e-con-full e-flex e-con e-child\" data-id=\"0e5d014\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0550f4b elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"0550f4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Customer Reviews<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e9e9c4 e-con-full e-flex e-con e-child\" data-id=\"6e9e9c4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49eca23 elementor-widget elementor-widget-bwp-testimonial\" data-id=\"49eca23\" data-element_type=\"widget\" data-widget_type=\"bwp-testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"bwp-testimonial carousel style-1\">\r\n\t\t<div class=\"bwp-swiper-slider swiper swiper-container-arrows-hover-show swiper-container-wrap-dots-outside\" data-swiper-id=\"49eca23\" data-slider-settings='{&quot;speed&quot;:500,&quot;slides_per_view&quot;:3,&quot;slides_to_scroll&quot;:1,&quot;space_between&quot;:30,&quot;auto_height&quot;:false,&quot;loop&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;show_arrows&quot;:true,&quot;slides_per_view_mobile&quot;:1,&quot;slides_to_scroll_mobile&quot;:1,&quot;space_between_mobile&quot;:15,&quot;slides_per_view_tablet&quot;:2,&quot;slides_to_scroll_tablet&quot;:1,&quot;space_between_tablet&quot;:15,&quot;slides_per_view_tablet_extra&quot;:3,&quot;space_between_tablet_extra&quot;:15}'>\r\n\t\t\t<div id=\"swiper-wrapper-6a57098c411b8\" class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide testimonial-container elementor-repeater-item-91d6906\">\r\n\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-testimonial\"><span>\"I am always impressed with the quality of the clothingat this store. The designs are not only stylish but alsodurable, and every...\"<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"fade-in lazyload\" src=\"https:\/\/orima.wpbingosite.com\/wp-content\/uploads\/2025\/04\/test.jpg\" alt=\"Image Testimonial\">\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"name-testimonial\"><span>Steve Jobs<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide testimonial-container elementor-repeater-item-2757fd4\">\r\n\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-testimonial\"><span>\"What I love most is how effortlessly their clothing combines elegance with everyday wearability. The fabrics feel premium,flattering.\"<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"fade-in lazyload\" src=\"https:\/\/orima.wpbingosite.com\/wp-content\/uploads\/2025\/04\/test-2.jpg\" alt=\"Image Testimonial\">\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"name-testimonial\"><span>Luca Moretti<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide testimonial-container elementor-repeater-item-70a32d8\">\r\n\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"description-testimonial\"><span>\"Their collections never disappoint. From the stitching to the silhouettes, you can feel the care put into every detail. I get compliment.\"<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"fade-in lazyload\" src=\"https:\/\/orima.wpbingosite.com\/wp-content\/uploads\/2025\/04\/test-3.jpg\" alt=\"Image Testimonial\">\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"name-testimonial\"><span>Ann Smith<\/span><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"bwp-slider-arrow bwp-swiper-button-prev swiper-button-prev-49eca23\"\n\t\t\t\t\tdata-widget-id=\"49eca23\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-arrows-hide-under=\"1600\"\n\t\t\t\t\t>\n\t\t\t\t\t<i class=\"icon-arrow-left\" aria-hidden=\"true\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"bwp-slider-arrow bwp-swiper-button-next swiper-button-next-49eca23\"\n\t\t\t\t\tdata-widget-id=\"49eca23\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tdata-arrows-hide-under=\"1600\"\n\t\t\t\t\t>\n\t\t\t\t\t<i class=\"icon-arrow-right\" aria-hidden=\"true\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"swiper-pagination swiper-pagination-49eca23\"\n\t\t\t\tdata-widget-id=\"49eca23\"\n\t\t\t\t\t\t\t\t\tdata-dots-hide-over=\"1600\"\n\t\t\t\t\t\t\t\t>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ABOUT US Retro Fashion Design Studio Welcome to Retro Fashion Design Studio, a boutique owned by DAYA SARA JACOB that specializes in handmade and self-designed clothes. Driven by a passion for fashion and unique designs, this business was created to share a vision of style. Explore our extensive collection that caters to various styles and [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-53501","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/pages\/53501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/comments?post=53501"}],"version-history":[{"count":37,"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/pages\/53501\/revisions"}],"predecessor-version":[{"id":67192,"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/pages\/53501\/revisions\/67192"}],"wp:attachment":[{"href":"https:\/\/mywatcheslists.com\/retro\/wp-json\/wp\/v2\/media?parent=53501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}